{"id":1022,"date":"2019-01-02T14:03:19","date_gmt":"2019-01-02T14:03:19","guid":{"rendered":"https:\/\/serch.es\/paddy\/"},"modified":"2019-01-02T14:18:50","modified_gmt":"2019-01-02T14:18:50","slug":"paddy","status":"publish","type":"post","link":"https:\/\/serch.es\/de\/paddy\/","title":{"rendered":"Paddy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1022\" class=\"elementor elementor-1022 elementor-203 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-563b67c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"563b67c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a0df00\" data-id=\"2a0df00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fb5076a elementor-widget elementor-widget-text-editor\" data-id=\"5fb5076a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Paddy hatte, als er noch jung war, einen schwerwiegenden Unfall. Wir vermuten, dass er an seinen Beinen gefesselt war, was zu einem schweren Sturz f\u00fchrte. Dabei erlitt er eine Verletzung an der Schulter sowie einen Beckenbruch.<\/p>\n<p>Nach einem Jahr intensiver Magnet-Therapie, musste er das Laufen erst wieder neu erlernen. Mittlerweile ist er ein schmerzfreies, gl\u00fcckliches Pony. Leider ist es aufgrund seiner Verletzungen und der intensiven Pflege, die er immer noch ben\u00f6tigt, nicht m\u00f6glich ein neues Zuhause f\u00fcr ihn zu finden. Wir gehen davon aus, dass Paddy ungef\u00e4hr 13 Jahre alt ist. Seit 9 Jahren lebt er bei uns und ist nun ein Mitglied der Herde. Er geniesst es in vollen Z\u00fcgen und hat einen starken Charakter entwickelt, was ihn sehr beliebt bei den anderen Pferden macht.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b2d08 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"70b2d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg\" alt=\"paddy-new2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new1.jpg\" alt=\"paddy-new1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/serch.es\/wp-content\/uploads\/2017\/01\/paddy.jpg\" alt=\"paddy\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b810966 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b810966\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c9be734\" data-id=\"7c9be734\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a84afbd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a84afbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15525fc4 elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"15525fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/serch.es\/de\/unsere-pferde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur\u00fcck zu 'Unsere Pferde'<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Paddy hatte, als er noch jung war, einen schwerwiegenden Unfall. Wir vermuten, dass er an seinen Beinen gefesselt war, was zu einem schweren Sturz f\u00fchrte. Dabei erlitt er eine Verletzung an der Schulter sowie einen Beckenbruch. Nach einem Jahr intensiver Magnet-Therapie, musste er das Laufen erst wieder neu erlernen. Mittlerweile ist er ein schmerzfreies, gl\u00fcckliches [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pferde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paddy - S.E.A.R.C.H.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serch.es\/de\/paddy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paddy - S.E.A.R.C.H.\" \/>\n<meta property=\"og:description\" content=\"Paddy hatte, als er noch jung war, einen schwerwiegenden Unfall. Wir vermuten, dass er an seinen Beinen gefesselt war, was zu einem schweren Sturz f\u00fchrte. Dabei erlitt er eine Verletzung an der Schulter sowie einen Beckenbruch. Nach einem Jahr intensiver Magnet-Therapie, musste er das Laufen erst wieder neu erlernen. Mittlerweile ist er ein schmerzfreies, gl\u00fcckliches [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serch.es\/de\/paddy\/\" \/>\n<meta property=\"og:site_name\" content=\"S.E.A.R.C.H.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpanishEquineAssociation\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-02T14:03:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-02T14:18:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Search-Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Search-Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/\"},\"author\":{\"name\":\"Search-Admin\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#\\\/schema\\\/person\\\/1b5a1dc32dd796cb31446e81dfbc7f94\"},\"headline\":\"Paddy\",\"datePublished\":\"2019-01-02T14:03:19+00:00\",\"dateModified\":\"2019-01-02T14:18:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/paddy-new2.jpg\",\"articleSection\":[\"Pferde\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/\",\"url\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/\",\"name\":\"Paddy - S.E.A.R.C.H.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/paddy-new2.jpg\",\"datePublished\":\"2019-01-02T14:03:19+00:00\",\"dateModified\":\"2019-01-02T14:18:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/paddy-new2.jpg\",\"contentUrl\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/paddy-new2.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/paddy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serch.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paddy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/serch.es\\\/de\\\/\",\"name\":\"S.E.A.R.C.H.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serch.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#organization\",\"name\":\"S.E.A.R.C.H.\",\"url\":\"https:\\\/\\\/serch.es\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/search-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/serch.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/search-logo.jpg\",\"width\":341,\"height\":223,\"caption\":\"S.E.A.R.C.H.\"},\"image\":{\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpanishEquineAssociation\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serch.es\\\/de\\\/#\\\/schema\\\/person\\\/1b5a1dc32dd796cb31446e81dfbc7f94\",\"name\":\"Search-Admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paddy - S.E.A.R.C.H.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serch.es\/de\/paddy\/","og_locale":"de_DE","og_type":"article","og_title":"Paddy - S.E.A.R.C.H.","og_description":"Paddy hatte, als er noch jung war, einen schwerwiegenden Unfall. Wir vermuten, dass er an seinen Beinen gefesselt war, was zu einem schweren Sturz f\u00fchrte. Dabei erlitt er eine Verletzung an der Schulter sowie einen Beckenbruch. Nach einem Jahr intensiver Magnet-Therapie, musste er das Laufen erst wieder neu erlernen. Mittlerweile ist er ein schmerzfreies, gl\u00fcckliches [&hellip;]","og_url":"https:\/\/serch.es\/de\/paddy\/","og_site_name":"S.E.A.R.C.H.","article_publisher":"https:\/\/www.facebook.com\/SpanishEquineAssociation\/","article_published_time":"2019-01-02T14:03:19+00:00","article_modified_time":"2019-01-02T14:18:50+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg","type":"image\/jpeg"}],"author":"Search-Admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Search-Admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/serch.es\/de\/paddy\/#article","isPartOf":{"@id":"https:\/\/serch.es\/de\/paddy\/"},"author":{"name":"Search-Admin","@id":"https:\/\/serch.es\/de\/#\/schema\/person\/1b5a1dc32dd796cb31446e81dfbc7f94"},"headline":"Paddy","datePublished":"2019-01-02T14:03:19+00:00","dateModified":"2019-01-02T14:18:50+00:00","mainEntityOfPage":{"@id":"https:\/\/serch.es\/de\/paddy\/"},"wordCount":137,"publisher":{"@id":"https:\/\/serch.es\/de\/#organization"},"image":{"@id":"https:\/\/serch.es\/de\/paddy\/#primaryimage"},"thumbnailUrl":"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg","articleSection":["Pferde"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/serch.es\/de\/paddy\/","url":"https:\/\/serch.es\/de\/paddy\/","name":"Paddy - S.E.A.R.C.H.","isPartOf":{"@id":"https:\/\/serch.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serch.es\/de\/paddy\/#primaryimage"},"image":{"@id":"https:\/\/serch.es\/de\/paddy\/#primaryimage"},"thumbnailUrl":"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg","datePublished":"2019-01-02T14:03:19+00:00","dateModified":"2019-01-02T14:18:50+00:00","breadcrumb":{"@id":"https:\/\/serch.es\/de\/paddy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serch.es\/de\/paddy\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/serch.es\/de\/paddy\/#primaryimage","url":"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg","contentUrl":"https:\/\/serch.es\/wp-content\/uploads\/2018\/11\/paddy-new2.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/serch.es\/de\/paddy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serch.es\/de\/"},{"@type":"ListItem","position":2,"name":"Paddy"}]},{"@type":"WebSite","@id":"https:\/\/serch.es\/de\/#website","url":"https:\/\/serch.es\/de\/","name":"S.E.A.R.C.H.","description":"","publisher":{"@id":"https:\/\/serch.es\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serch.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/serch.es\/de\/#organization","name":"S.E.A.R.C.H.","url":"https:\/\/serch.es\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/serch.es\/de\/#\/schema\/logo\/image\/","url":"https:\/\/serch.es\/wp-content\/uploads\/2016\/10\/search-logo.jpg","contentUrl":"https:\/\/serch.es\/wp-content\/uploads\/2016\/10\/search-logo.jpg","width":341,"height":223,"caption":"S.E.A.R.C.H."},"image":{"@id":"https:\/\/serch.es\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpanishEquineAssociation\/"]},{"@type":"Person","@id":"https:\/\/serch.es\/de\/#\/schema\/person\/1b5a1dc32dd796cb31446e81dfbc7f94","name":"Search-Admin"}]}},"_links":{"self":[{"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/posts\/1022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/comments?post=1022"}],"version-history":[{"count":0,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/posts\/1022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/media\/895"}],"wp:attachment":[{"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/media?parent=1022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/categories?post=1022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serch.es\/de\/wp-json\/wp\/v2\/tags?post=1022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}